{"id":24187,"date":"2020-02-19T13:17:49","date_gmt":"2020-02-19T12:17:49","guid":{"rendered":"https:\/\/rosacadaques.com\/uncategorized\/rideau-rosa"},"modified":"2022-08-31T07:20:58","modified_gmt":"2022-08-31T05:20:58","slug":"rideau-rosa","status":"publish","type":"product","link":"https:\/\/www.rosacadaques.com\/en\/uncategorized-en\/rideau-rosa\/","title":{"rendered":"Rosa dried flowers curtain"},"content":{"rendered":"<p style=\"text-align: center;\">Composition of the <strong>Rosa curtain<\/strong> :<\/p>\n<p style=\"text-align: center;\">White Oats, Pink Gypsophila, White Hydrangea, Delphinium, White Limonium<\/p>\n<p style=\"text-align: center;\">Height: 2 meter<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"woocommerce-product-details__short-description\">\n<p>We have imagined a beautiful curtain with hanging<span class=\"Apple-converted-space\">\u00a0 <\/span>flowers to decorate your wedding! They will dress up your walls and give a country style to your event. An original idea for the decoration of your photo spaces (photobooth) or to announce your table plan.<\/p>\n<p>A decoration that will last over time. We advise you to order your wedding decorations 3 weeks before the day, and to keep them away from the sun.<\/p>\n<\/div>\n","protected":false},"featured_media":24143,"template":"","meta":[],"product_cat":[2795],"product_tag":[],"giftcard-category":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v14.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Rosa dried flowers curtain - Rosa Cadaque\u0301s<\/title>\n<meta name=\"robots\" content=\"index, follow\" \>\n<meta name=\"googlebot\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \>\n<meta name=\"bingbot\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \>\n<link rel=\"canonical\" href=\"https:\/\/www.rosacadaques.com\/en\/uncategorized-en\/rideau-rosa\/\" \>\n<meta property=\"og:locale\" content=\"en_US\" \>\n<meta property=\"og:type\" content=\"article\" \>\n<meta property=\"og:title\" content=\"Rosa dried flowers curtain - rosa cadaque\u0301s\" \>\n<meta property=\"og:description\" content=\"We have imagined a beautiful curtain with hanging\u00a0 flowers to decorate your wedding! they will dress up walls and give country style event. an original idea for the decoration of photo spaces (photobooth) or announce table plan. that last over time. we advise you order wedding decorations 3 weeks before day, keep them away from sun.\" \>\n<meta property=\"og:url\" content=\"https:\/\/www.rosacadaques.com\/en\/uncategorized-en\/rideau-rosa\/\" \>\n<meta property=\"og:site_name\" content=\"Rosa cadaque\u0301s\" \>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RosaCadaques0\/\" \>\n<meta property=\"article:modified_time\" content=\"2022-08-31T05:20:58+00:00\" \>\n<meta property=\"og:image\" content=\"https:\/\/www.rosacadaques.com\/wp-content\/uploads\/DSCF0260-1.jpg\" \>\n\t<meta property=\"og:image:width\" content=\"827\" \>\n\t<meta property=\"og:image:height\" content=\"1000\" \>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.rosacadaques.com\/en\/#organization\",\"name\":\"Rosa Cadaqu\\u00e9s\",\"url\":\"https:\/\/www.rosacadaques.com\/en\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/RosaCadaques0\/\",\"https:\/\/www.instagram.com\/rosacadaques\/\",\"https:\/\/www.linkedin.com\/company\/rosa-cadaques\/\",\"https:\/\/www.youtube.com\/channel\/UCUaQJZSdtlS73QTu6ReYr7A\/featured\",\"https:\/\/www.pinterest.fr\/rosacadaques\/\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.rosacadaques.com\/en\/#logo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/www.rosacadaques.com\/wp-content\/uploads\/Logotype-rosa-facturation.jpg\",\"width\":198,\"height\":92,\"caption\":\"Rosa Cadaqu\\u00e9s\"},\"image\":{\"@id\":\"https:\/\/www.rosacadaques.com\/en\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.rosacadaques.com\/en\/#website\",\"url\":\"https:\/\/www.rosacadaques.com\/en\/\",\"name\":\"Rosa Cadaque\\u0301s\",\"description\":\"Fleurs s\\u00e9ch\\u00e9es made in Rosa Cadaqu\\u00e9s : d\\u00e9couvrez notre s\\u00e9l\\u00e9ction de Bouquets de Fleurs S\\u00e9ch\\u00e9es confectionn\\u00e9s \\u00e0 la main dans notre Atelier.\",\"publisher\":{\"@id\":\"https:\/\/www.rosacadaques.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.rosacadaques.com\/en\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.rosacadaques.com\/en\/uncategorized-en\/rideau-rosa\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/www.rosacadaques.com\/wp-content\/uploads\/DSCF0260-1.jpg\",\"width\":827,\"height\":1000,\"caption\":\"Rideau en fleurs s\\u00e9ch\\u00e9es collection mariage, rideau en fleurs s\\u00e9ch\\u00e9es dans des tons roses\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.rosacadaques.com\/en\/uncategorized-en\/rideau-rosa\/#webpage\",\"url\":\"https:\/\/www.rosacadaques.com\/en\/uncategorized-en\/rideau-rosa\/\",\"name\":\"Rosa dried flowers curtain - Rosa Cadaque\\u0301s\",\"isPartOf\":{\"@id\":\"https:\/\/www.rosacadaques.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.rosacadaques.com\/en\/uncategorized-en\/rideau-rosa\/#primaryimage\"},\"datePublished\":\"2020-02-19T12:17:49+00:00\",\"dateModified\":\"2022-08-31T05:20:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.rosacadaques.com\/en\/uncategorized-en\/rideau-rosa\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.rosacadaques.com\/en\/uncategorized-en\/rideau-rosa\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.rosacadaques.com\/en\/uncategorized-en\/rideau-rosa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/rosacadaques.com\/en\/\",\"url\":\"https:\/\/rosacadaques.com\/en\/\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/rosacadaques.com\/en\/all-our-dried-flowers\/\",\"url\":\"https:\/\/rosacadaques.com\/en\/all-our-dried-flowers\/\",\"name\":\"All our dried flowers\"}},{\"@type\":\"ListItem\",\"position\":3,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.rosacadaques.com\/en\/events\/\",\"url\":\"https:\/\/www.rosacadaques.com\/en\/events\/\",\"name\":\"Dried flowers wedding\"}},{\"@type\":\"ListItem\",\"position\":4,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.rosacadaques.com\/en\/garlands-and-curtains-of-dried-flowers\/\",\"url\":\"https:\/\/www.rosacadaques.com\/en\/garlands-and-curtains-of-dried-flowers\/\",\"name\":\"Dried flower garland\"}},{\"@type\":\"ListItem\",\"position\":5,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.rosacadaques.com\/en\/uncategorized-en\/rideau-rosa\/\",\"url\":\"https:\/\/www.rosacadaques.com\/en\/uncategorized-en\/rideau-rosa\/\",\"name\":\"Rosa dried flowers curtain\"}}]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","_links":{"self":[{"href":"https:\/\/www.rosacadaques.com\/en\/wp-json\/wp\/v2\/product\/24187"}],"collection":[{"href":"https:\/\/www.rosacadaques.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.rosacadaques.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rosacadaques.com\/en\/wp-json\/wp\/v2\/media\/24143"}],"wp:attachment":[{"href":"https:\/\/www.rosacadaques.com\/en\/wp-json\/wp\/v2\/media?parent=24187"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.rosacadaques.com\/en\/wp-json\/wp\/v2\/product_cat?post=24187"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.rosacadaques.com\/en\/wp-json\/wp\/v2\/product_tag?post=24187"},{"taxonomy":"giftcard-category","embeddable":true,"href":"https:\/\/www.rosacadaques.com\/en\/wp-json\/wp\/v2\/giftcard-category?post=24187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}